{"id":4900,"date":"2016-10-23T17:00:58","date_gmt":"2016-10-23T15:00:58","guid":{"rendered":"https:\/\/fjungclaus.de\/wp\/?p=4900"},"modified":"2019-05-18T20:43:28","modified_gmt":"2019-05-18T18:43:28","slug":"5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22","status":"publish","type":"post","link":"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22","title":{"rendered":"5. RP-Ultralauf von Steinhude nach Bad M\u00fcnder, 53km, 2016-10-22"},"content":{"rendered":"<p>Die Urkunde sagt:<\/p>\n<blockquote><p>Geschafft, 53km auf dem europ\u00e4ischen Fernwanderweg E1 mit anstrengenden 1000 H\u00f6henmetern im Deister von Steinhude nach Bad M\u00fcnder.<\/p><\/blockquote>\n<p>Meine Uhr sagte hinterher sogar 55,4km &#8230; und \u00fcber die Zeit &#8230; da schweigen wir lieber &#8230;<\/p>\n<p>Ein grauer und k\u00fchler Herbsttag mit 7\u00b0C. Aber auch dieser hatte landschaftlich seinen Reiz.<br \/>\nZwar keinerlei Sonne, zum Gl\u00fcck aber auch keinerlei Regen.<br \/>\nAuf Grund des Niederschlags in der vergangenen Woche gab es jedoch erfreulich viel Matsch auf manchem Weg \ud83d\ude09<\/p>\n<p>Danke an <a href=\"http:\/\/running-paule.de\/\">Detlef<\/a>, sowie an\u00a0<a href=\"http:\/\/janbergmann.npage.de\/\">Jan<\/a>\u00a0und seinen Vater f\u00fcr die Organisation und Unterst\u00fctzung bei diesem sch\u00f6nen Lauf. Ich hoffe nat\u00fcrlich auf eine Wiederholung.<\/p>\n<div data-carousel-extra='{\"blog_id\":1,\"permalink\":\"https:\\\/\\\/fjungclaus.de\\\/wp\\\/2016\\\/10\\\/23\\\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\"}' class=\"tiled-gallery type-rectangular\" data-original-width=\"1130\"><div class=\"gallery-row\" style=\"width: 1125px; height: 298px;\"><div class=\"gallery-group images-1\" style=\"width: 470px; height: 302px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_5944_rot\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4903\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5944_rot.jpg\" data-orig-size=\"1024,655\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477124147&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;23&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.0125&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;25&quot;}\" data-image-title=\"img_5944_rot\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5944_rot-640x409.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5944_rot.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5944_rot.jpg\" width=\"466\" height=\"298\" align=\"left\" title=\"img_5944_rot\" \/><\/a><div class=\"tiled-gallery-caption\">Das Starterfeld<\/div><\/div><\/div><div class=\"gallery-group images-1\" style=\"width: 452px; height: 302px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_5957\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4904\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5957.jpg\" data-orig-size=\"1024,682\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;7.1&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477124382&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;40&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_5957\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5957-640x426.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5957.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5957.jpg\" width=\"448\" height=\"298\" align=\"left\" title=\"img_5957\" \/><\/a><div class=\"tiled-gallery-caption\">Steinhude<\/div><\/div><\/div><div class=\"gallery-group images-1\" style=\"width: 203px; height: 302px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_5941\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4902\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5941.jpg\" data-orig-size=\"682,1024\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477123950&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;29&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.0166666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;25&quot;}\" data-image-title=\"img_5941\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5941-426x640.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5941.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5941.jpg\" width=\"199\" height=\"298\" align=\"left\" title=\"img_5941\" \/><\/a><div class=\"tiled-gallery-caption\">Letzte Instruktionen vom &#8220;Chef&#8221; vor dem Start<\/div><\/div><\/div><\/div><div class=\"gallery-row\" style=\"width: 1125px; height: 791px;\"><div class=\"gallery-group images-2\" style=\"width: 594px; height: 795px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_5958\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4905\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5958.jpg\" data-orig-size=\"1024,682\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;10&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477124409&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;40&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_5958\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5958-640x426.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5958.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5958.jpg\" width=\"590\" height=\"394\" align=\"left\" title=\"img_5958\" \/><\/a><div class=\"tiled-gallery-caption\">Steinhude<\/div><\/div><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_5959\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4906\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5959.jpg\" data-orig-size=\"1024,682\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;9&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477124453&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;17&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_5959\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5959-640x426.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5959.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5959.jpg\" width=\"590\" height=\"393\" align=\"left\" title=\"img_5959\" \/><\/a><div class=\"tiled-gallery-caption\">Steinhude<\/div><\/div><\/div><div class=\"gallery-group images-1\" style=\"width: 531px; height: 795px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_5961\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4907\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5961.jpg\" data-orig-size=\"682,1024\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;7.1&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477124540&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;40&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_5961\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5961-426x640.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5961.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5961.jpg\" width=\"527\" height=\"791\" align=\"left\" title=\"img_5961\" \/><\/a><div class=\"tiled-gallery-caption\">Steinhude<\/div><\/div><\/div><\/div><div class=\"gallery-row\" style=\"width: 1125px; height: 265px;\"><div class=\"gallery-group images-1\" style=\"width: 402px; height: 269px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_5965\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4908\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5965.jpg\" data-orig-size=\"1024,682\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;9&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477124676&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;17&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_5965\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5965-640x426.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5965.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5965.jpg\" width=\"398\" height=\"265\" align=\"left\" title=\"img_5965\" \/><\/a><div class=\"tiled-gallery-caption\">Steinhude<\/div><\/div><\/div><div class=\"gallery-group images-1\" style=\"width: 181px; height: 269px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_5966-2\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4909\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5966.jpg\" data-orig-size=\"682,1024\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477124688&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;40&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_5966\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5966-426x640.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5966.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5966.jpg\" width=\"177\" height=\"265\" align=\"left\" title=\"img_5966\" \/><\/a><div class=\"tiled-gallery-caption\">Steinhude<\/div><\/div><\/div><div class=\"gallery-group images-1\" style=\"width: 181px; height: 269px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_5969\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4910\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5969.jpg\" data-orig-size=\"682,1024\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477124801&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;95&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_5969\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5969-426x640.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5969.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5969.jpg\" width=\"177\" height=\"265\" align=\"left\" title=\"img_5969\" \/><\/a><div class=\"tiled-gallery-caption\">Steinhude<\/div><\/div><\/div><div class=\"gallery-group images-1\" style=\"width: 181px; height: 269px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_5977\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4911\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5977.jpg\" data-orig-size=\"682,1024\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;7.1&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477124956&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;30&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_5977\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5977-426x640.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5977.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5977.jpg\" width=\"177\" height=\"265\" align=\"left\" title=\"img_5977\" \/><\/a><div class=\"tiled-gallery-caption\">Steinhude<\/div><\/div><\/div><div class=\"gallery-group images-1\" style=\"width: 180px; height: 269px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_5978\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4912\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5978.jpg\" data-orig-size=\"682,1024\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;10&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477124980&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;25&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_5978\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5978-426x640.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5978.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5978.jpg\" width=\"176\" height=\"265\" align=\"left\" title=\"img_5978\" \/><\/a><div class=\"tiled-gallery-caption\">Steinhude<\/div><\/div><\/div><\/div><div class=\"gallery-row\" style=\"width: 1125px; height: 497px;\"><div class=\"gallery-group images-1\" style=\"width: 751px; height: 501px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_5982\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4913\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5982.jpg\" data-orig-size=\"1024,682\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477125538&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;40&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_5982\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5982-640x426.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5982.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5982.jpg\" width=\"747\" height=\"497\" align=\"left\" title=\"img_5982\" \/><\/a><div class=\"tiled-gallery-caption\">Steinhude<\/div><\/div><\/div><div class=\"gallery-group images-2\" style=\"width: 374px; height: 501px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_5986\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4914\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5986.jpg\" data-orig-size=\"1024,682\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477125646&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;175&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.002&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_5986\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5986-640x426.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5986.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5986.jpg\" width=\"370\" height=\"247\" align=\"left\" title=\"img_5986\" \/><\/a><div class=\"tiled-gallery-caption\">Steinhude<\/div><\/div><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_5994\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4915\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5994.jpg\" data-orig-size=\"1024,682\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477125838&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;200&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.002&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_5994\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5994-640x426.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5994.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_5994.jpg\" width=\"370\" height=\"246\" align=\"left\" title=\"img_5994\" \/><\/a><div class=\"tiled-gallery-caption\">Ein Reiher, der glaubt eine M\u00f6we zu sein \ud83d\ude09<\/div><\/div><\/div><\/div><div class=\"gallery-row\" style=\"width: 1125px; height: 1099px;\"><div class=\"gallery-group images-1\" style=\"width: 736px; height: 1103px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_6009\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4916\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6009.jpg\" data-orig-size=\"682,1024\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;11&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477133017&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;29&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_6009\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6009-426x640.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6009.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6009.jpg\" width=\"732\" height=\"1099\" align=\"left\" title=\"img_6009\" \/><\/a><div class=\"tiled-gallery-caption\">Steinhude<\/div><\/div><\/div><div class=\"gallery-group images-3\" style=\"width: 389px; height: 1103px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_6013\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4917\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6013.jpg\" data-orig-size=\"1024,682\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;11&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477135412&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;8&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;25&quot;}\" data-image-title=\"img_6013\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6013-640x426.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6013.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6013.jpg\" width=\"385\" height=\"257\" align=\"left\" title=\"img_6013\" \/><\/a><div class=\"tiled-gallery-caption\">Steinhude<\/div><\/div><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_6017\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4918\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6017.jpg\" data-orig-size=\"1024,682\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477142414&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;17&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.0025&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_6017\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6017-640x426.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6017.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6017.jpg\" width=\"385\" height=\"256\" align=\"left\" title=\"img_6017\" \/><\/a><div class=\"tiled-gallery-caption\">VP3 Nienstedter Pass<\/div><\/div><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_6018\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4919\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6018.jpg\" data-orig-size=\"682,1024\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477142452&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;40&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.002&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_6018\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6018-426x640.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6018.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6018.jpg\" width=\"385\" height=\"578\" align=\"left\" title=\"img_6018\" \/><\/a><div class=\"tiled-gallery-caption\">Nienstedter Pass<\/div><\/div><\/div><\/div><div class=\"gallery-row\" style=\"width: 1125px; height: 247px;\"><div class=\"gallery-group images-1\" style=\"width: 375px; height: 251px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_6028\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4920\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6028.jpg\" data-orig-size=\"1024,682\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477142607&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;17&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_6028\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6028-640x426.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6028.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6028.jpg\" width=\"371\" height=\"247\" align=\"left\" title=\"img_6028\" \/><\/a><div class=\"tiled-gallery-caption\">VP3 Nienstedter Pass<\/div><\/div><\/div><div class=\"gallery-group images-1\" style=\"width: 375px; height: 251px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_6037-2\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4921\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6037.jpg\" data-orig-size=\"1024,682\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477143510&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;40&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.0025&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_6037\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6037-640x426.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6037.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6037.jpg\" width=\"371\" height=\"247\" align=\"left\" title=\"img_6037\" \/><\/a><div class=\"tiled-gallery-caption\">Nienstedter Pass<\/div><\/div><\/div><div class=\"gallery-group images-1\" style=\"width: 375px; height: 251px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_6041-2\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4922\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6041.jpg\" data-orig-size=\"1024,682\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477143550&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;17&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_6041\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6041-640x426.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6041.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6041.jpg\" width=\"371\" height=\"247\" align=\"left\" title=\"img_6041\" \/><\/a><div class=\"tiled-gallery-caption\">VP3 Nienstedter Pass<\/div><\/div><\/div><\/div><div class=\"gallery-row\" style=\"width: 1125px; height: 317px;\"><div class=\"gallery-group images-1\" style=\"width: 480px; height: 321px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_6043-2\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4923\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6043.jpg\" data-orig-size=\"1024,682\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;6.3&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477144542&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;40&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_6043\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6043-640x426.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6043.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6043.jpg\" width=\"476\" height=\"317\" align=\"left\" title=\"img_6043\" \/><\/a><div class=\"tiled-gallery-caption\">Herbst 1<\/div><\/div><\/div><div class=\"gallery-group images-1\" style=\"width: 215px; height: 321px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_6048\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4924\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6048.jpg\" data-orig-size=\"682,1024\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477145463&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;26&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.025&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_6048\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6048-426x640.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6048.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6048.jpg\" width=\"211\" height=\"317\" align=\"left\" title=\"img_6048\" \/><\/a><div class=\"tiled-gallery-caption\">Herbst 2<\/div><\/div><\/div><div class=\"gallery-group images-1\" style=\"width: 215px; height: 321px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_6049\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4925\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6049.jpg\" data-orig-size=\"682,1024\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477145500&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;17&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.0333333333333&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_6049\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6049-426x640.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6049.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6049.jpg\" width=\"211\" height=\"317\" align=\"left\" title=\"img_6049\" \/><\/a><div class=\"tiled-gallery-caption\">Herbst 3<\/div><\/div><\/div><div class=\"gallery-group images-1\" style=\"width: 215px; height: 321px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_6053\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4926\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6053.jpg\" data-orig-size=\"682,1024\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477147160&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;17&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_6053\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6053-426x640.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6053.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6053.jpg\" width=\"211\" height=\"317\" align=\"left\" title=\"img_6053\" \/><\/a><div class=\"tiled-gallery-caption\">Herbst 4<\/div><\/div><\/div><\/div><div class=\"gallery-row\" style=\"width: 1125px; height: 310px;\"><div class=\"gallery-group images-1\" style=\"width: 470px; height: 314px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_6055_tmap\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4927\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6055_tmap.jpg\" data-orig-size=\"1024,682\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477148987&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;40&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/1&quot;,&quot;flash&quot;:&quot;25&quot;}\" data-image-title=\"img_6055_tmap\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6055_tmap-640x426.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6055_tmap.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6055_tmap.jpg\" width=\"466\" height=\"310\" align=\"left\" title=\"img_6055_tmap\" \/><\/a><div class=\"tiled-gallery-caption\">Deister<\/div><\/div><\/div><div class=\"gallery-group images-1\" style=\"width: 237px; height: 314px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_8925\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4930\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8925.jpg\" data-orig-size=\"768,1024\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon PowerShot SX280 HS&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477126921&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.5&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.0125&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_8925\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8925-480x640.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8925.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8925.jpg\" width=\"233\" height=\"310\" align=\"left\" title=\"img_8925\" \/><\/a><div class=\"tiled-gallery-caption\">Steinhude<\/div><\/div><\/div><div class=\"gallery-group images-1\" style=\"width: 418px; height: 314px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_8931\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4931\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8931.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon PowerShot SX280 HS&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477127614&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.5&quot;,&quot;iso&quot;:&quot;250&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_8931\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8931-640x480.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8931.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8931.jpg\" width=\"414\" height=\"310\" align=\"left\" title=\"img_8931\" \/><\/a><div class=\"tiled-gallery-caption\">Steinhude Richtung Hagenburg<\/div><\/div><\/div><\/div><div class=\"gallery-row\" style=\"width: 1125px; height: 790px;\"><div class=\"gallery-group images-2\" style=\"width: 528px; height: 794px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_8940\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4932\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8940.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon PowerShot SX280 HS&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477128044&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.5&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_8940\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8940-640x480.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8940.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8940.jpg\" width=\"524\" height=\"393\" align=\"left\" title=\"img_8940\" \/><\/a><div class=\"tiled-gallery-caption\">Hagenburg<\/div><\/div><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_8949\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4933\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8949.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon PowerShot SX280 HS&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477128506&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;13.418&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_8949\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8949-640x480.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8949.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8949.jpg\" width=\"524\" height=\"393\" align=\"left\" title=\"img_8949\" \/><\/a><div class=\"tiled-gallery-caption\">Hagenburger Schloss \/ Kanal<\/div><\/div><\/div><div class=\"gallery-group images-1\" style=\"width: 597px; height: 794px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_8956-2\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4934\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8956.jpg\" data-orig-size=\"768,1024\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon PowerShot SX280 HS&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477128564&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;23.576&quot;,&quot;iso&quot;:&quot;800&quot;,&quot;shutter_speed&quot;:&quot;0.025&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_8956\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8956-480x640.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8956.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8956.jpg\" width=\"593\" height=\"790\" align=\"left\" title=\"img_8956\" \/><\/a><\/div><\/div><\/div><div class=\"gallery-row\" style=\"width: 1125px; height: 938px;\"><div class=\"gallery-group images-1\" style=\"width: 708px; height: 942px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_8964-2\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4935\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8964.jpg\" data-orig-size=\"768,1024\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon PowerShot SX280 HS&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477130309&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;9.874&quot;,&quot;iso&quot;:&quot;800&quot;,&quot;shutter_speed&quot;:&quot;0.05&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_8964\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8964-480x640.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8964.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8964.jpg\" width=\"704\" height=\"938\" align=\"left\" title=\"img_8964\" \/><\/a><\/div><\/div><div class=\"gallery-group images-3\" style=\"width: 417px; height: 942px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_8966\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4936\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8966.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon PowerShot SX280 HS&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477130397&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;12.669&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.0025&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_8966\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8966-640x480.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8966.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8966.jpg\" width=\"413\" height=\"310\" align=\"left\" title=\"img_8966\" \/><\/a><div class=\"tiled-gallery-caption\">Kaliberg Wunstorf \/ Bokeloh<\/div><\/div><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_8973\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4937\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8973.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon PowerShot SX280 HS&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477130416&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;33.638&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_8973\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8973-640x480.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8973.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8973.jpg\" width=\"413\" height=\"310\" align=\"left\" title=\"img_8973\" \/><\/a><div class=\"tiled-gallery-caption\">Kaliberg Wunstorf \/ Bokeloh<\/div><\/div><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_8991\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4938\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8991.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon PowerShot SX280 HS&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477133568&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.5&quot;,&quot;iso&quot;:&quot;500&quot;,&quot;shutter_speed&quot;:&quot;0.0333333333333&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_8991\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8991-640x480.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8991.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8991.jpg\" width=\"413\" height=\"310\" align=\"left\" title=\"img_8991\" \/><\/a><div class=\"tiled-gallery-caption\">VP1 bei Haste<\/div><\/div><\/div><\/div><div class=\"gallery-row\" style=\"width: 1125px; height: 317px;\"><div class=\"gallery-group images-1\" style=\"width: 242px; height: 321px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_8993\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4939\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8993.jpg\" data-orig-size=\"768,1024\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon PowerShot SX280 HS&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477133583&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.5&quot;,&quot;iso&quot;:&quot;500&quot;,&quot;shutter_speed&quot;:&quot;0.0333333333333&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_8993\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8993-480x640.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8993.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_8993.jpg\" width=\"238\" height=\"317\" align=\"left\" title=\"img_8993\" \/><\/a><div class=\"tiled-gallery-caption\">VP1 bei Haste<\/div><\/div><\/div><div class=\"gallery-group images-1\" style=\"width: 426px; height: 321px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_9001\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4940\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_9001.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon PowerShot SX280 HS&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477138242&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;8.044&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_9001\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_9001-640x480.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_9001.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_9001.jpg\" width=\"422\" height=\"317\" align=\"left\" title=\"img_9001\" \/><\/a><div class=\"tiled-gallery-caption\">Kurpark Bad Nenndorf<\/div><\/div><\/div><div class=\"gallery-group images-1\" style=\"width: 242px; height: 321px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_9004\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4941\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_9004.jpg\" data-orig-size=\"768,1024\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon PowerShot SX280 HS&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477144688&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.5&quot;,&quot;iso&quot;:&quot;800&quot;,&quot;shutter_speed&quot;:&quot;0.04&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_9004\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_9004-480x640.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_9004.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_9004.jpg\" width=\"238\" height=\"317\" align=\"left\" title=\"img_9004\" \/><\/a><div class=\"tiled-gallery-caption\">Kurpark Bad Nenndorf<\/div><\/div><\/div><div class=\"gallery-group images-1\" style=\"width: 215px; height: 321px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_6073\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4928\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6073.jpg\" data-orig-size=\"682,1024\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477151956&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;30&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.0166666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;0\\\/3&quot;,&quot;flash&quot;:&quot;25&quot;}\" data-image-title=\"img_6073\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6073-426x640.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6073.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6073.jpg\" width=\"211\" height=\"317\" align=\"left\" title=\"img_6073\" \/><\/a><div class=\"tiled-gallery-caption\">Die Beiden sind auch endlich im Ziel<\/div><\/div><\/div><\/div><div class=\"gallery-row\" style=\"width: 1125px; height: 514px;\"><div class=\"gallery-group images-1\" style=\"width: 776px; height: 518px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/img_6089_tmap\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4929\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6089_tmap.jpg\" data-orig-size=\"1024,682\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 30D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477155542&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;28&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;exposure_bias&quot;:&quot;-1\\\/1&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"img_6089_tmap\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6089_tmap-640x426.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6089_tmap.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/img_6089_tmap.jpg\" width=\"772\" height=\"514\" align=\"left\" title=\"img_6089_tmap\" \/><\/a><div class=\"tiled-gallery-caption\">Nach dem Lauf ein Panorama, das ein wenig an Alpenfernblick erinnert<\/div><\/div><\/div><div class=\"gallery-group images-2\" style=\"width: 349px; height: 518px;\"><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/2016-10-23-16-13-04\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4901\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/2016-10-23-16-13-04.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.7&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;SM-G930F&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1477239184&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.2&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.04&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;latitude_ref&quot;:&quot;N&quot;,&quot;longitude_ref&quot;:&quot;E&quot;,&quot;exposure_bias&quot;:&quot;0\\\/10&quot;}\" data-image-title=\"2016-10-23-16-13-04\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/2016-10-23-16-13-04-640x480.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/2016-10-23-16-13-04.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/2016-10-23-16-13-04.jpg\" width=\"345\" height=\"259\" align=\"left\" title=\"2016-10-23-16-13-04\" \/><\/a><div class=\"tiled-gallery-caption\">Pokale 2014 und 2016<\/div><\/div><div class=\"tiled-gallery-item tiled-gallery-item-full\"><a href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\/strecke-5ter-rp-ultra-2016-10-23\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4942\" data-orig-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/strecke-5ter-rp-ultra-2016-10-23.jpg\" data-orig-size=\"1280,931\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"strecke-5ter-rp-ultra-2016-10-23\" data-image-description=\"\" data-medium-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/strecke-5ter-rp-ultra-2016-10-23-640x466.jpg\" data-large-file=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/strecke-5ter-rp-ultra-2016-10-23.jpg\" src=\"https:\/\/fjungclaus.de\/wp\/wp-content\/uploads\/2016\/10\/strecke-5ter-rp-ultra-2016-10-23.jpg\" width=\"345\" height=\"251\" align=\"left\" title=\"strecke-5ter-rp-ultra-2016-10-23\" \/><\/a><div class=\"tiled-gallery-caption\">Die Strecke<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die Urkunde sagt: Geschafft, 53km auf dem europ\u00e4ischen Fernwanderweg E1 mit anstrengenden 1000 H\u00f6henmetern im Deister von Steinhude nach Bad M\u00fcnder. Meine Uhr sagte hinterher sogar 55,4km &#8230; und \u00fcber die Zeit &#8230; da schweigen wir lieber &#8230; Ein grauer&#8230; <a class=\"more-link\" href=\"https:\/\/fjungclaus.de\/wp\/2016\/10\/23\/5-rp-ultralauf-von-steinhude-nach-bad-muender-53km-2016-10-22\">Continue Reading &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":4936,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[45,73,175,71],"class_list":["post-4900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-running","tag-deister","tag-running-paule-de","tag-steinhuder-meer","tag-ultra"],"views":3144,"_links":{"self":[{"href":"https:\/\/fjungclaus.de\/wp\/wp-json\/wp\/v2\/posts\/4900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fjungclaus.de\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fjungclaus.de\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fjungclaus.de\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fjungclaus.de\/wp\/wp-json\/wp\/v2\/comments?post=4900"}],"version-history":[{"count":2,"href":"https:\/\/fjungclaus.de\/wp\/wp-json\/wp\/v2\/posts\/4900\/revisions"}],"predecessor-version":[{"id":11401,"href":"https:\/\/fjungclaus.de\/wp\/wp-json\/wp\/v2\/posts\/4900\/revisions\/11401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fjungclaus.de\/wp\/wp-json\/wp\/v2\/media\/4936"}],"wp:attachment":[{"href":"https:\/\/fjungclaus.de\/wp\/wp-json\/wp\/v2\/media?parent=4900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fjungclaus.de\/wp\/wp-json\/wp\/v2\/categories?post=4900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fjungclaus.de\/wp\/wp-json\/wp\/v2\/tags?post=4900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}